{"id":36326,"date":"2022-09-01T19:31:46","date_gmt":"2022-09-01T19:31:46","guid":{"rendered":"https:\/\/milicia-pro.com\/?post_type=product&#038;p=36326"},"modified":"2025-09-24T17:39:34","modified_gmt":"2025-09-24T17:39:34","slug":"navalha-deejo-37gr-hunting-scene-titanium-madeira-coral","status":"publish","type":"product","link":"https:\/\/milicia-pro.com\/index.php\/product\/navalha-deejo-37gr-hunting-scene-titanium-madeira-coral\/","title":{"rendered":"NAVALHA DEEJO, 37GR, HUNTING SCENE, TITANIUM, MADEIRA CORAL"},"content":{"rendered":"<p>Faca ultraleve em a\u00e7o inoxid\u00e1vel Z40C13, acabamento fosco. Sistema de bloqueio da lamina seguro decorado com grava\u00e7\u00e3o a laser fina. \u00a0Clip para prender no cinto. Cabo em madeira de coral. Coralwood (ou Padauk) \u00e9 uma madeira abundante tradicionalmente usada em talheres por seus requintados destaques vermelhos e \u00e2mbar (o motivo de seu nome), sua robustez e sua excecional resist\u00eancia \u00e0 humidade. Coralwood destaca primorosamente a eleg\u00e2ncia de uma faca Deejo.<\/p>\n<p>ESPECIFICA\u00c7\u00d5ES<\/p>\n<p>37 G DE PESO\/ Z40C13 A\u00c7O INOXID\u00c1VEL \/11 CM QUANDO FECHADA \/ 20,5 CM QUANDO ABERTA \/ 9,5 CM DE L\u00c2MINA \/ 0,9 CM DE ESPESSURA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faca ultraleve em a\u00e7o inoxid\u00e1vel Z40C13, acabamento fosco. Sistema de bloqueio da lamina seguro decorado com grava\u00e7\u00e3o a laser fina. \u00a0Clip para prender no cinto. Cabo em madeira de coral. Coralwood (ou Padauk) \u00e9 uma madeira abundante tradicionalmente usada em talheres por seus requintados destaques vermelhos e \u00e2mbar (o motivo de seu nome), sua robustez [&#8230;]\n","protected":false},"featured_media":36477,"comment_status":"open","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[1506],"product_cat":[1065,831,829,1098],"product_tag":[912,225],"class_list":{"0":"post-36326","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-deejo","7":"product_cat-cutelariaferramentas","8":"product_cat-deejo","9":"product_cat-marcas","10":"product_cat-navalha","11":"product_tag-cutelaria","12":"product_tag-navalha","14":"first","15":"instock","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/milicia-pro.com\/index.php\/wp-json\/wp\/v2\/product\/36326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/milicia-pro.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/milicia-pro.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/milicia-pro.com\/index.php\/wp-json\/wp\/v2\/comments?post=36326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/milicia-pro.com\/index.php\/wp-json\/wp\/v2\/media\/36477"}],"wp:attachment":[{"href":"https:\/\/milicia-pro.com\/index.php\/wp-json\/wp\/v2\/media?parent=36326"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/milicia-pro.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=36326"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/milicia-pro.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=36326"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/milicia-pro.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=36326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}